{"id":12326,"date":"2021-07-28T18:00:20","date_gmt":"2021-07-28T18:00:20","guid":{"rendered":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/?p=12326"},"modified":"2021-07-29T11:40:53","modified_gmt":"2021-07-29T11:40:53","slug":"top-5-maravillosos-tesoros-escondidos-de-centroamerica","status":"publish","type":"post","link":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/","title":{"rendered":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-12330\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\" alt=\"Tesoros escondidos centroamerica\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg 1800w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-300x200.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-1024x683.jpg 1024w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-768x512.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-1536x1024.jpg 1536w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-696x464.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-1068x712.jpg 1068w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-630x420.jpg 630w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-1200x800.jpg 1200w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica-500x333.jpg 500w\" sizes=\"(max-width: 1800px) 100vw, 1800px\" \/> \u00a0<strong>Fuente: <a href=\"https:\/\/listindiario.com\/economia\/2021\/07\/01\/677400\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\" target=\"_blank\" rel=\"noopener\">Listin Diario<\/a><\/strong><\/p>\n<p>La posici\u00f3n geogr\u00e1fica de\u00a0Centroam\u00e9rica\u00a0permite que este territorio albergue algunas de las maravillas naturales m\u00e1s asombrosas del mundo.\u00a0Tierra de imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee\u00a0destinos\u00a0que sorprender\u00e1n a cualquier que se atreva a descubrirlos.<\/p>\n<p>Para ello hemos preparado una selecci\u00f3n de algunos de los\u00a0tesoros\u00a0que aguardan a ser revelados por los turistas en\u00a0Centroam\u00e9rica<\/p>\n<h3>Parque Nacional Coiba\/Panam\u00e1<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-12332\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301.jpg\" alt=\"Parque Nacional Coiba\/Panam\u00e1\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301.jpg 1024w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301-300x200.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301-768x512.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301-696x464.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301-630x420.jpg 630w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/sitios-turi\u0301sticos-Panama\u0301-500x333.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Este archipi\u00e9lago, probablemente, se encuentra entre las zonas m\u00e1s v\u00edrgenes y de mayor\u00a0abundancia natural\u00a0en toda\u00a0Centroam\u00e9rica. La cantidad de especies marinas que habitan en la zona permite que ah\u00ed se pueda vivir una de las mejores\u00a0experiencias de buceo.<\/p>\n<h3>Bosque Nuboso Monteverde\/Costa Rica<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-12334\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica.jpg\" alt=\"Bosque Nuboso Monteverde\/Costa Rica\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica.jpg 1024w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica-300x200.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica-768x512.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica-696x464.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica-631x420.jpg 631w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/bosque-nuboso-costa-rica-500x333.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Una\u00a0atm\u00f3sfera brumosa\u00a0abraza a este codiciado\u00a0destino ecotur\u00edstico, cuya reserva abarca 26,000 acres de extensi\u00f3n, rebosantes de una maravillosa diversidad de vida silvestre y vegetal. En el\u00a0bosque nuboso\u00a0es posible recorrer senderos que atraviesan la selva tropical a trav\u00e9s de una buena dosis de\u00a0neblina\u00a0que esconde esta singular reserva.<\/p>\n<h3>Cataratas Pulhapanzak\/Honduras<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-12336\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras.jpg\" alt=\"Cataratas Pulhapanzak\/Honduras\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras.jpg 1024w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-300x225.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-768x576.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-696x522.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-560x420.jpg 560w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-80x60.jpg 80w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-265x198.jpg 265w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Cataratas-Honduras-500x375.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>A 17 kil\u00f3metros del enigm\u00e1tico\u00a0Lago de Yojoa\u00a0se encuentra una imponente ca\u00edda de 43 metros de altura, uno de los destinos predilectos de los hondure\u00f1os. No s\u00f3lo por sus maravillosos\u00a0paisajes naturales, sino tambi\u00e9n porque posee importantes\u00a0vestigios precolombinos\u00a0que se encuentran dentro del mismo balneario.<\/p>\n<h3>Las Islas del Ma\u00edz\/Nicaragua<\/h3>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-12338\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua.jpg\" alt=\"Las Islas del Ma\u00edz\/Nicaragua\" width=\"100%\" height=\"auto\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua.jpg 1024w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua-300x199.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua-768x510.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua-696x462.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua-632x420.jpg 632w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/Islas-del-maiz-nicaragua-500x332.jpg 500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>Sus\u00a0arenas blancas, aguas color turquesa y bosques cocoteros\u00a0convierten a este\u00a0archipi\u00e9lago\u00a0en un tesoro de Centroam\u00e9rica que a\u00f1o con a\u00f1o atrae a miles de turistas. Estas islas ofrecen la posibilidad de explorar el\u00a0lado caribe\u00f1o de Nicaragua\u00a0y su belleza natural casi desconocida.<\/p>\n<h3>Semuc Champey\/ Guatemala<\/h3>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12340\" src=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala.jpg\" alt=\"Semuc Champey\/ Guatemala\" width=\"960\" height=\"640\" srcset=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala.jpg 960w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala-300x200.jpg 300w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala-768x512.jpg 768w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala-696x464.jpg 696w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala-630x420.jpg 630w, https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/semuc-champei-guatemala-500x333.jpg 500w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/h3>\n<p>Este monumento natural se ubica en la provincia de\u00a0Alta Verapaz\u00a0y est\u00e1 rodeado por una\u00a0exuberante vegetaci\u00f3n\u00a0y hermosas pozas que esconde con recelo. Sus aguas cristalinas conforman, pr\u00e1cticamente,\u00a0piscinas naturales\u00a0color jade en forma de escaleras.<\/p>\n<p>Estas cinco propuestas son aut\u00e9nticos\u00a0tesoros naturales\u00a0que resguarda\u00a0Centroam\u00e9rica\u00a0para hacer que los turistas se reconecten con su entorno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Fuente: Listin Diario La posici\u00f3n geogr\u00e1fica de\u00a0Centroam\u00e9rica\u00a0permite que este territorio albergue algunas de las maravillas naturales m\u00e1s asombrosas del mundo.\u00a0Tierra de imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee\u00a0destinos\u00a0que sorprender\u00e1n a cualquier que se atreva a descubrirlos. Para ello hemos preparado una selecci\u00f3n de algunos de los\u00a0tesoros\u00a0que aguardan a ser revelados por los [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12330,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,32,25],"tags":[],"class_list":{"0":"post-12326","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aventura","8":"category-naturaleza","9":"category-viajar"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa<\/title>\n<meta name=\"description\" content=\"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa\" \/>\n<meta property=\"og:description\" content=\"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/\" \/>\n<meta property=\"og:site_name\" content=\"Sala de prensa\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-28T18:00:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-29T11:40:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Denis Alvarado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Denis Alvarado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/\"},\"author\":{\"name\":\"Denis Alvarado\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/#\\\/schema\\\/person\\\/0aa3bd0dbaabaead6089ee3dd0cd7ae5\"},\"headline\":\"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica\",\"datePublished\":\"2021-07-28T18:00:20+00:00\",\"dateModified\":\"2021-07-29T11:40:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/\"},\"wordCount\":363,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\",\"articleSection\":[\"Aventura\",\"Naturaleza\",\"Viajar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/\",\"url\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/\",\"name\":\"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\",\"datePublished\":\"2021-07-28T18:00:20+00:00\",\"dateModified\":\"2021-07-29T11:40:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/#\\\/schema\\\/person\\\/0aa3bd0dbaabaead6089ee3dd0cd7ae5\"},\"description\":\"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg\",\"width\":1800,\"height\":1200,\"caption\":\"Tesoros escondidos centroamerica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/viajar\\\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/#website\",\"url\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/\",\"name\":\"Sala de prensa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/#\\\/schema\\\/person\\\/0aa3bd0dbaabaead6089ee3dd0cd7ae5\",\"name\":\"Denis Alvarado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g\",\"caption\":\"Denis Alvarado\"},\"url\":\"https:\\\/\\\/www.visitcentroamerica.com\\\/sala-prensa\\\/author\\\/denis\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa","description":"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/","og_locale":"es_ES","og_type":"article","og_title":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa","og_description":"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.","og_url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/","og_site_name":"Sala de prensa","article_published_time":"2021-07-28T18:00:20+00:00","article_modified_time":"2021-07-29T11:40:53+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg","type":"image\/jpeg"}],"author":"Denis Alvarado","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Denis Alvarado","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#article","isPartOf":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/"},"author":{"name":"Denis Alvarado","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/#\/schema\/person\/0aa3bd0dbaabaead6089ee3dd0cd7ae5"},"headline":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica","datePublished":"2021-07-28T18:00:20+00:00","dateModified":"2021-07-29T11:40:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/"},"wordCount":363,"commentCount":0,"image":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg","articleSection":["Aventura","Naturaleza","Viajar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/","url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/","name":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica - Sala de prensa","isPartOf":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#primaryimage"},"image":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg","datePublished":"2021-07-28T18:00:20+00:00","dateModified":"2021-07-29T11:40:53+00:00","author":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/#\/schema\/person\/0aa3bd0dbaabaead6089ee3dd0cd7ae5"},"description":"Imponentes volcanes, abundantes bosques y apacibles lagos, el Istmo posee destinos que sorprender\u00e1n a cualquier que se atreva a descubrirlos.","breadcrumb":{"@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#primaryimage","url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg","contentUrl":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-content\/uploads\/2021\/07\/top-5-maravillosos-tesoros-escondidos-de-centroamerica.jpg","width":1800,"height":1200,"caption":"Tesoros escondidos centroamerica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/viajar\/top-5-maravillosos-tesoros-escondidos-de-centroamerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/"},{"@type":"ListItem","position":2,"name":"Top 5: Maravillosos tesoros escondidos de Centroam\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/#website","url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/","name":"Sala de prensa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/#\/schema\/person\/0aa3bd0dbaabaead6089ee3dd0cd7ae5","name":"Denis Alvarado","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c31f0697f6edb7c68d5dedc2ccbd548d2a9f73aa293e81c6a1425229ec4c9135?s=96&d=mm&r=g","caption":"Denis Alvarado"},"url":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/author\/denis\/"}]}},"_links":{"self":[{"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/posts\/12326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/comments?post=12326"}],"version-history":[{"count":9,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/posts\/12326\/revisions"}],"predecessor-version":[{"id":12363,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/posts\/12326\/revisions\/12363"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/media\/12330"}],"wp:attachment":[{"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/media?parent=12326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/categories?post=12326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.visitcentroamerica.com\/sala-prensa\/wp-json\/wp\/v2\/tags?post=12326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}